{"id":5,"name":".\u304a\u5ba2\u69d8\u30b5\u30dd\u30fc\u30c8\u30bb\u30f3\u30bf\u30fc","url":"","description":"","link":"http:\/\/www.chi-chi-bu.com\/en\/author\/ma1n-secur-acc0unt2\/","slug":"ma1n-secur-acc0unt2","meta":[],"_links":{"self":[{"href":"http:\/\/www.chi-chi-bu.com\/en\/wp-json\/wp\/v2\/users\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.chi-chi-bu.com\/en\/wp-json\/wp\/v2\/users"}]}}